{"id":16895,"date":"2024-01-12T00:17:07","date_gmt":"2024-01-12T00:17:07","guid":{"rendered":"http:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/"},"modified":"2024-01-12T00:17:10","modified_gmt":"2024-01-12T00:17:10","slug":"dm212f5-summertime-santa","status":"publish","type":"product","link":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/","title":{"rendered":"DM212F5  Summertime Santa"},"content":{"rendered":"<p>DM212F5 Fountains Summertime Santa<\/p>\n<p>Packing [4\/1] CBM 0.076<\/p>\n<p>You will want to celebrate like it is Christmas when you see this great fountain.  Red, green, silver, and gold are featured with exciting crackle to add sound effects.<\/p>\n<p>Video Link <a href=\"http:\/\/dominatorfireworks.com\/video\/DM212F5.mp4\">dominatorfireworks.com\/video\/DM212F5.mp4<\/a><\/p>\n<p>https:\/\/youtu.be\/RdJnsqiXIos<\/p>\n<p>Length  Width  Height <\/p>\n<p>UPC 851866001751<\/p>\n","protected":false},"excerpt":{"rendered":"<p>You will want to celebrate like it is Christmas when you see this great fountain.  Red, green, silver, and gold are featured with exciting crackle to add sound effects.<\/p>\n","protected":false},"featured_media":16166,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[232],"product_tag":[],"class_list":{"0":"post-16895","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fountains","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DM212F5 Summertime Santa -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DM212F5 Summertime Santa -\" \/>\n<meta property=\"og:description\" content=\"You will want to celebrate like it is Christmas when you see this great fountain. Red, green, silver, and gold are featured with exciting crackle to add sound effects.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-12T00:17:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DM212F5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"597\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/\",\"url\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/\",\"name\":\"DM212F5 Summertime Santa -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DM212F5.jpg\",\"datePublished\":\"2024-01-12T00:17:07+00:00\",\"dateModified\":\"2024-01-12T00:17:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DM212F5.jpg\",\"contentUrl\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DM212F5.jpg\",\"width\":600,\"height\":597},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dm212f5-summertime-santa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product Line\",\"item\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product-line\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DM212F5 Summertime Santa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DM212F5 Summertime Santa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/","og_locale":"en_US","og_type":"article","og_title":"DM212F5 Summertime Santa -","og_description":"You will want to celebrate like it is Christmas when you see this great fountain. Red, green, silver, and gold are featured with exciting crackle to add sound effects.","og_url":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/","article_modified_time":"2024-01-12T00:17:10+00:00","og_image":[{"width":600,"height":597,"url":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DM212F5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/","url":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/","name":"DM212F5 Summertime Santa -","isPartOf":{"@id":"https:\/\/dominatorfireworks.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/#primaryimage"},"image":{"@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/#primaryimage"},"thumbnailUrl":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DM212F5.jpg","datePublished":"2024-01-12T00:17:07+00:00","dateModified":"2024-01-12T00:17:10+00:00","breadcrumb":{"@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/#primaryimage","url":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DM212F5.jpg","contentUrl":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DM212F5.jpg","width":600,"height":597},{"@type":"BreadcrumbList","@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dm212f5-summertime-santa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dominatorfireworks.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Product Line","item":"https:\/\/dominatorfireworks.com\/blog\/product-line\/"},{"@type":"ListItem","position":3,"name":"DM212F5 Summertime Santa"}]},{"@type":"WebSite","@id":"https:\/\/dominatorfireworks.com\/blog\/#website","url":"https:\/\/dominatorfireworks.com\/blog\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dominatorfireworks.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product\/16895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/comments?post=16895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/media\/16166"}],"wp:attachment":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/media?parent=16895"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product_brand?post=16895"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product_cat?post=16895"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product_tag?post=16895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}