{"id":16475,"date":"2024-01-12T00:10:15","date_gmt":"2024-01-12T00:10:15","guid":{"rendered":"http:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/"},"modified":"2024-01-12T00:10:17","modified_gmt":"2024-01-12T00:10:17","slug":"dmp5494-new-crossettes","status":"publish","type":"product","link":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/","title":{"rendered":"DMP5494 New  Crossettes"},"content":{"rendered":"<p>2024 New Item<\/p>\n<p>DMP5494 New New Fireworks Crossettes<\/p>\n<p>Packing [4\/1] CBM 0.072<\/p>\n<p>36 fanned shots of strobe mines and colorful crossettes<\/p>\n<p>Video Link <a href=\"http:\/\/dominatorfireworks.com\/video\/DMP5494.mp4\">dominatorfireworks.com\/video\/DMP5494.mp4<\/a><\/p>\n<p>Length 14.6 Width 11 Height 6.8<\/p>\n<p>UPC 8.51866E+11<\/p>\n","protected":false},"excerpt":{"rendered":"<p>36 fanned shots of strobe mines and colorful crossettes<\/p>\n","protected":false},"featured_media":15859,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[120],"product_tag":[],"class_list":{"0":"post-16475","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-new-fireworks","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DMP5494 New Crossettes -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DMP5494 New Crossettes -\" \/>\n<meta property=\"og:description\" content=\"36 fanned shots of strobe mines and colorful crossettes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-12T00:10:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DMP5494-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/\",\"url\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/\",\"name\":\"DMP5494 New Crossettes -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DMP5494-4.jpg\",\"datePublished\":\"2024-01-12T00:10:15+00:00\",\"dateModified\":\"2024-01-12T00:10:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DMP5494-4.jpg\",\"contentUrl\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/DMP5494-4.jpg\",\"width\":600,\"height\":325},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product\\\/dmp5494-new-crossettes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product Line\",\"item\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/product-line\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DMP5494 New Crossettes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dominatorfireworks.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DMP5494 New Crossettes -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/","og_locale":"en_US","og_type":"article","og_title":"DMP5494 New Crossettes -","og_description":"36 fanned shots of strobe mines and colorful crossettes","og_url":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/","article_modified_time":"2024-01-12T00:10:17+00:00","og_image":[{"width":600,"height":325,"url":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DMP5494-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/","url":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/","name":"DMP5494 New Crossettes -","isPartOf":{"@id":"https:\/\/dominatorfireworks.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/#primaryimage"},"image":{"@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/#primaryimage"},"thumbnailUrl":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DMP5494-4.jpg","datePublished":"2024-01-12T00:10:15+00:00","dateModified":"2024-01-12T00:10:17+00:00","breadcrumb":{"@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/#primaryimage","url":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DMP5494-4.jpg","contentUrl":"https:\/\/dominatorfireworks.com\/blog\/wp-content\/uploads\/2024\/01\/DMP5494-4.jpg","width":600,"height":325},{"@type":"BreadcrumbList","@id":"https:\/\/dominatorfireworks.com\/blog\/product\/dmp5494-new-crossettes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dominatorfireworks.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Product Line","item":"https:\/\/dominatorfireworks.com\/blog\/product-line\/"},{"@type":"ListItem","position":3,"name":"DMP5494 New Crossettes"}]},{"@type":"WebSite","@id":"https:\/\/dominatorfireworks.com\/blog\/#website","url":"https:\/\/dominatorfireworks.com\/blog\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dominatorfireworks.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product\/16475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/comments?post=16475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/media\/15859"}],"wp:attachment":[{"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/media?parent=16475"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product_brand?post=16475"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product_cat?post=16475"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dominatorfireworks.com\/blog\/wp-json\/wp\/v2\/product_tag?post=16475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}